{"id":9,"date":"2025-11-18T13:05:30","date_gmt":"2025-11-18T12:05:30","guid":{"rendered":"https:\/\/lescabanesjuandco.fr\/?page_id=9"},"modified":"2026-03-23T22:51:20","modified_gmt":"2026-03-23T21:51:20","slug":"elementor-9","status":"publish","type":"page","link":"https:\/\/lescabanesjuandco.fr\/en\/","title":{"rendered":"Ju &amp; Co Cabins"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9\" class=\"elementor elementor-9\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e7e7342 e-flex e-con-boxed e-con e-parent\" data-id=\"4e7e7342\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:&quot;1409&quot;,&quot;url&quot;:&quot;https:\\\/\\\/lescabanesjuandco.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/0.png&quot;},{&quot;id&quot;:&quot;1273&quot;,&quot;url&quot;:&quot;https:\\\/\\\/lescabanesjuandco.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/tonneau-1000050740.jpg&quot;},{&quot;id&quot;:&quot;1354&quot;,&quot;url&quot;:&quot;https:\\\/\\\/lescabanesjuandco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/0.jpg&quot;},{&quot;id&quot;:&quot;1314&quot;,&quot;url&quot;:&quot;https:\\\/\\\/lescabanesjuandco.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/tonneau-1000050833.jpg&quot;},{&quot;id&quot;:&quot;1291&quot;,&quot;url&quot;:&quot;https:\\\/\\\/lescabanesjuandco.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1000050915.jpg&quot;},{&quot;id&quot;:&quot;1432&quot;,&quot;url&quot;:&quot;https:\\\/\\\/lescabanesjuandco.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/0-4.jpg&quot;},{&quot;id&quot;:&quot;1433&quot;,&quot;url&quot;:&quot;https:\\\/\\\/lescabanesjuandco.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/0-5-1.jpg&quot;}],&quot;shape_divider_bottom&quot;:&quot;pyramids&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M761.9,44.1L643.1,27.2L333.8,98L0,3.8V0l1000,0v3.9\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a858cbd e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"6a858cbd\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-10ac845a e-con-full e-flex e-con e-child\" data-id=\"10ac845a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5f5ff29f e-con-full e-flex e-con e-child\" data-id=\"5f5ff29f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ddc64cd elementor-widget elementor-widget-heading\" data-id=\"1ddc64cd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Slow Living atypique au bord d'un lac<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c873804 elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"6c873804\" data-element_type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;JU &amp; CO&quot;,&quot;marker&quot;:&quot;underline_zigzag&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t\t\t\t<h1 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Les Cabanes<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">JU &amp; CO<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4322417f e-con-full e-flex e-con e-child\" data-id=\"4322417f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c567d5e elementor-widget elementor-widget-heading\" data-id=\"c567d5e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Entre for\u00eat et lac, d\u00e9couvrez une parenth\u00e8se suspendue, pens\u00e9e pour la d\u00e9tente, l\u2019\u00e9vasion et les instants pr\u00e9cieux en famille ou en amoureux.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92a6e4b e-flex e-con-boxed e-con e-parent\" data-id=\"92a6e4b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b240e8b elementor-widget elementor-widget-shortcode\" data-id=\"b240e8b\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64ea0895 e-flex e-con-boxed e-con e-parent\" data-id=\"64ea0895\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-13bae650 e-con-full e-flex e-con e-child\" data-id=\"13bae650\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3cde4c6d e-con-full e-flex e-con e-child\" data-id=\"3cde4c6d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ba98175 elementor--v-position-bottom elementor--h-position-center elementor-arrows-position-inside elementor-pagination-position-inside elementor-invisible elementor-widget elementor-widget-slides\" data-id=\"1ba98175\" data-element_type=\"widget\" data-settings=\"{&quot;transition&quot;:&quot;fade&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;200&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-945d97f swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"lobservatoire\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><h5 class=\"elementor-slide-heading\">Un endroit convivial<\/h5><p class=\"elementor-slide-description\">O\u00f9 l'on vient faire des rencontres ... o\u00f9 l'on respire. <\/p><\/div><\/div><\/div><div class=\"elementor-repeater-item-9cb7d37 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"tonneau-1000050408\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><h5 class=\"elementor-slide-heading\">Profitez du lac<\/h5><p class=\"elementor-slide-description\">P\u00eache ou d\u00e9tente, \u00e0 vous de choisir! <\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4773064b e-con-full e-flex e-con e-child\" data-id=\"4773064b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-cd461ff e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"cd461ff\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;400&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-722dadef elementor-widget elementor-widget-heading\" data-id=\"722dadef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Faites de votre s\u00e9jour un moment suspendu<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74938d15 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"74938d15\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;600&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e2fbb25 elementor-widget elementor-widget-heading\" data-id=\"4e2fbb25\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Au bord du lac du Rousset, nich\u00e9 au c\u0153ur d\u2019un hectare de nature pr\u00e9serv\u00e9e, Les Cabanes ju&amp;co vous accueillent dans un \u00e9crin o\u00f9 le temps ralentit. Ici, le murmure de la for\u00eat, la vue imprenable sur l\u2019eau et le calme enveloppant invitent \u00e0 d\u00e9connecter pour de le temps d'une pause \u00e0 deux ou en famille.<br><br>\nEntre pontons, bois et lumi\u00e8re douce, les h\u00e9bergements sont pens\u00e9s pour respirer, se retrouver et vivre un s\u00e9jour simple et authentique.\n<br><br>\n\u00c0 quelques pas des cabanes, les plaisirs se partagent : parties de p\u00e9tanque au soleil, parcours sant\u00e9 \u00e0 l\u2019ombre des arbres, petites aires de jeux pour les enfants, observation des oiseaux depuis l\u2019observatoire, balades en famille ou escapades \u00e0 deux, sans oublier le restaurant du lac o\u00f9 savourer une cuisine locale au fil de l\u2019eau.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2212509a elementor-icon-list--layout-inline elementor-mobile-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2212509a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><path d=\"M85.58 392.5c.4687 0 .9375-.0469 1.406-.125c4.344-.7813 7.25-4.938 6.469-9.281c-3.688-20.67-9.938-42.22-45.09-78.33C34.3 290.3 33.08 269.9 31.77 248.4c-1-16.55-2.031-33.66-8.875-49.59C11.55 172.3 14.3 142.1 30.05 120.1c3.625-5.031 7.906-9.516 12.72-13.31c12.69-9.953 22.88-24.14 29.47-41C77.71 51.83 86.14 40.23 97.33 31.33c11.94-9.531 26.03-14.77 41.19-15.14C153.1 15.08 167.6 18.86 180.3 27.17c11.75 7.719 21.06 18.39 27.59 31.75c2 3.984 6.844 5.562 10.72 3.656c3.969-1.953 5.594-6.75 3.656-10.72c-7.844-15.95-19-28.77-33.19-38.06C173.5 3.562 155.6-1.056 137.7 .208C119.5 .6611 102 7.094 87.33 18.83C73.93 29.5 63.83 43.34 57.36 59.95C51.8 74.16 43.33 86 32.89 94.2C26.86 98.94 21.55 104.5 17.05 110.8c-19 26.5-22.38 62.66-8.844 94.33C13.93 218.5 14.83 233.5 15.8 249.4c1.406 23.48 2.875 47.75 21.12 66.48c34.63 35.59 38.03 54.66 40.78 69.98C78.39 389.7 81.77 392.5 85.58 392.5zM573.3 96.91c-4.938-23.09-16.66-44.02-33.59-60.22c-16.38-17.23-37.22-28.98-60.28-33.95c-21.19-4.576-42.28-3.373-62.47 3.484c-17.91 6.094-36.31 7.234-53.31 3.453c-9.375-2.141-19.08-2.843-28.39-2.218c-40.22 2.578-74.86 28.23-90.42 67.08C238.1 91.2 225.7 104.3 212.5 118.2C193.2 138.5 173.3 159.4 173.3 192.1c0 59.38-9.344 71.56-19.25 84.47c-12.53 16.36-25.5 33.28-26.03 116.2c-.0781 11.95 3.963 23.24 11.13 32.69l-.7705 .7607c-.0098 .0098 .0098-.0098 0 0L66.33 498.3c-3.125 3.125-3.125 8.188 0 11.31C67.89 511.2 69.96 512 71.99 512c2.062 0 4.094-.7813 5.656-2.344l71.1-72.09l.873-.8711c10.15 7.484 22.6 11.84 35.54 11.84c81.69 0 98.03-12.81 113.8-25.22c12.66-9.906 24.59-19.27 84.63-19.27c32.59 0 53.5-20.02 73.72-39.36c13.81-13.23 26.88-25.72 43.5-32.42c38.69-15.59 64.13-50.47 66.72-90.83c.5938-9.516-.0052-19-2.099-28.34c-3.812-17.11-2.625-35.61 3.406-53.5C576.7 139.3 577.8 118.2 573.3 96.91zM554.6 154.5c-6.969 20.66-8.312 42.14-3.875 62.11c1.781 7.891 2.438 15.95 1.938 23.95c-2.188 34.16-24 63.63-56.94 76.89c-19.47 7.859-34.25 22.02-48.56 35.7c-18.75 17.95-36.5 34.92-62.66 34.92c-65.56 0-80.25 11.53-94.47 22.67c-13.69 10.72-27.85 21.81-104 21.81c-8.629 0-16.57-3.215-23.6-7.773L331.3 256h108.7c4.406 0 8-3.578 8-8s-3.594-8-8-8h-92.73l98.39-98.36c3.125-3.121 3.125-8.176 0-11.3c-3.156-3.152-8.219-3.09-11.31 0L271.1 292.6V200c0-4.422-3.594-8-8-8s-8 3.578-8 8v108.1c0 .1387 .1387 .2168 .1465 .3535l-105.2 105.2c-4.152-6.244-7.014-13.18-6.967-20.76c.5-77.58 11.81-92.33 22.75-106.6c11.59-15.12 22.53-29.39 22.53-94.2c0-26.27 16.91-44.06 34.81-62.91C237.7 114.8 251.8 100 259.7 80.47c13.22-33.05 42.6-54.94 76.6-57.11c1.75-.1094 3.5-.1719 5.281-.1719c6.188 0 12.41 .7031 18.56 2.094c19.91 4.438 41.31 3.109 61.97-3.906c17.5-5.938 35.63-6.969 53.94-3.016c19.91 4.312 37.91 14.45 52.34 29.62c14.88 14.23 24.97 32.31 29.28 52.28C561.6 118.7 560.6 136.9 554.6 154.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Paisible et calme<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M320 111.1C320 103.2 327.2 95.1 336 95.1C344.8 95.1 352 103.2 352 111.1C352 120.8 344.8 127.1 336 127.1C327.2 127.1 320 120.8 320 111.1zM284.8 388.4L350.9 499.9C353.1 503.7 351.9 508.6 348.1 510.9C344.3 513.1 339.4 511.9 337.1 508.1L269 393.1C251.6 397.6 233.4 400 214.7 400C209.2 400 203.7 399.8 198.3 399.4L254.1 500.1C257.1 503.9 255.8 508.8 251.9 510.1C248.1 513.1 243.2 511.8 241 507.9L178.6 396.1C77.69 379.8 0 292.2 0 186.7C0 171.9 11.94 160 26.67 160H192C209.7 160 224 145.7 224 128V104C224 46.56 270.6 0 328 0C374.5 0 413.8 30.5 427.2 72.57L508.1 121.1C510.5 122.6 512 125.2 512 127.1C512 130.8 510.5 133.4 508.1 134.9L432 180.5V183.1C432 278.8 370.1 359.3 284.8 388.4V388.4zM240 103.1V127.1C240 154.5 218.5 175.1 192 175.1H26.67C20.78 175.1 16 180.8 16 186.7C16 295.5 105.5 384 214.7 384C325.2 384 416 294.3 416 183.1V103.1C416 96.77 415.1 89.74 413.5 83.02L413 82.74L413.3 82.28C403.6 44.18 369.1 15.1 328 15.1C279.4 15.1 240 55.4 240 103.1zM432 161.9L488.5 127.1L431.5 93.83C431.8 97.18 432 100.6 432 103.1L432 161.9z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">En pleine nature<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M329.3 304c-12.57 0-25.25 4.949-34.68 14.22l-6.652 6.523L281.3 318.2C271.9 308.9 259.3 304 246.7 304c-30.31 0-45.08 25.67-45.08 44.75c0 11.55 4.478 23.1 13.43 31.91l65.3 64.22c2.109 2.074 4.847 3.098 7.614 3.098c2.77 0 5.569-1.023 7.679-3.098l65.3-64.22c8.976-8.821 13.46-20.38 13.46-31.93C374.4 330 359.6 304 329.3 304zM358.4 348.8c0 7.721-3.051 14.95-8.685 20.48l-61.73 60.71l-61.72-60.7c-5.613-5.526-8.656-12.75-8.656-20.47C217.6 324.7 240.2 320 246.7 320c8.693 0 17.24 3.504 23.46 9.641l17.85 17.51l17.87-17.52C312.1 323.5 320.6 320 329.3 320C351.2 320 358.4 339.4 358.4 348.8zM456.4 96c-22.06 0-40 17.94-40 40V240c0 4.406-3.594 8-8.141 8c-4.406 0-8-3.594-8-8V72c0-22.06-17.94-40-40-40s-40 17.94-40 40L320 240c0 4.406-3.425 8-7.831 8s-8-3.594-8-8V40c0-22.06-18.06-40-40.12-40S224.2 17.94 224.2 40L224.1 240c0 4.406-3.448 8-7.854 8S208.1 244.4 208.1 240l.1092-168c0-22.06-18.04-40-40.11-40S128.2 49.94 128.2 72v252.9L79.89 277.2C71.04 268.4 59.09 263.5 46.52 263.5c-10.5 0-45.82 8.397-45.82 45.91c0 12.73 5.001 25.69 14.75 35.44l107.9 108.1C161.3 491 211.8 512 265.6 512h62.73c92.64 0 168-75.36 168-168v-208C496.4 113.9 478.4 96 456.4 96zM480.4 344c0 83.81-68.19 152-152 152h-62.73c-49.5 0-96.03-19.3-131-54.34l-107.9-108.1c-6.67-6.679-10.11-15.51-10.11-24.1c0-18.88 15.92-29.95 30.2-29.95c8.109 0 15.94 3.234 21.73 9.062l62 61.14c1.523 1.503 3.542 2.291 5.604 2.291c4.543 0 8.021-3.664 8.021-7.994v-272c0-13.23 10.77-24 24-24s24 10.77 24 24L192.1 240c0 13.23 10.91 24 24.15 24S240.1 253.2 240.1 240l.1093-200c0-13.23 10.77-24 24-24s24 10.77 24 24L288 240c0 13.23 10.94 24 24.17 24s24-10.77 24-24V72c0-13.23 10.77-24 24-24s24 10.77 24 24L384.1 240c0 13.23 10.91 24 24.29 24c13.23 0 24-10.77 24-24V136c0-13.23 10.77-24 24-24s24 10.77 24 24V344z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pour d\u00e9connecter<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40e2e334 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"40e2e334\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;800&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68cd4a8f elementor-widget elementor-widget-image\" data-id=\"68cd4a8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo-1-1024x1024.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-152\" alt=\"\" srcset=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo-1-1024x1024.png 1024w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo-1-300x300.png 300w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo-1-150x150.png 150w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo-1-768x768.png 768w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo-1-1536x1536.png 1536w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo-1.png 1542w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1316c6dd e-con-full e-flex e-con e-child\" data-id=\"1316c6dd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f619556 elementor-widget elementor-widget-heading\" data-id=\"2f619556\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Votre h\u00f4te<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40381ca9 elementor-widget elementor-widget-heading\" data-id=\"40381ca9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Coraline et son mari vous accueillent toute l'ann\u00e9e<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6da21f19 e-con-full e-flex e-con e-parent\" data-id=\"6da21f19\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-21cca1b8 e-con-full e-flex e-con e-child\" data-id=\"21cca1b8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6c148f18 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"6c148f18\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-568368fd elementor-widget elementor-widget-heading\" data-id=\"568368fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un Cadre id\u00e9al<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c527586 elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"2c527586\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir les h\u00e9bergements<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15f40a5a e-con-full e-flex e-con e-child\" data-id=\"15f40a5a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-79435c4c e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"79435c4c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;400&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4c40ecfe e-con-full e-flex e-con e-child\" data-id=\"4c40ecfe\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23192036 elementor-widget elementor-widget-image\" data-id=\"23192036\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/fishing-rod.svg\" class=\"attachment-large size-large wp-image-326\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38526fd9 elementor-widget elementor-widget-heading\" data-id=\"38526fd9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">P\u00eache au Lac du Rousset<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d679502 elementor-widget elementor-widget-heading\" data-id=\"2d679502\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00c0 quelques pas des cabanes, le lac de 55 hectares est un petit paradis pour les amateurs de p\u00eache.\nNous proposons en option :<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ae3a0 elementor-icon-list--layout-inline elementor-mobile-align-center elementor-align-left elementor-widget__width-inherit elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d6ae3a0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M384 288c-8.836 0-16 7.158-16 15.1c0 8.836 7.164 15.1 16 15.1s16-7.164 16-15.1C400 295.2 392.8 288 384 288zM421.5 460.6C446.8 435.6 480 393.5 480 344.4c0-81.05-88.07-136.4-96-136.4c-6.707 0-96 54.84-96 136.4c0 49.04 33.22 91.19 58.52 116.2l-16.25 27.2C328.8 490.3 327.1 493.2 327.1 495.1C327.1 504.5 334.9 512 344 512h80c9.26 0 16-7.572 16-16c0-2.842-.7563-5.682-2.266-8.207L421.5 460.6zM344 496l22.84-38.23C343.3 436.6 304 393.8 304 344.4c0-70.42 80-120.4 80-120.4s80 49.99 80 120.4c0 49.43-39.35 92.19-62.84 113.4L424 496H344zM320.1 16.02c18.89 0 55.89 14.66 55.89 56.02v87.97c0 4.406 3.594 7.1 8 7.1s8-3.594 8-7.1V72.04C392 19.11 345.4 0 320.2 0c-5.867 0-11.8 .7231-17.64 2.194L239.5 17.98C150.3 40.22 88 120 88 211.1v76.03L80 288c-26.51 0-48 21.49-48 47.1v127.1C32 490.5 53.49 512 80 512h32C138.5 512 160 490.5 160 464V336c0-26.51-21.49-47.1-48-47.1L104 288V211.1c0-84.59 57.31-157.1 139.4-178.5l63.03-15.78C310.1 16.57 315.6 16.02 320.1 16.02zM112 304c17.64 0 32 14.36 32 31.1v127.1c0 17.64-14.36 31.1-32 31.1h-32c-17.64 0-32-14.36-32-31.1v-127.1c0-17.64 14.36-31.1 32-31.1H112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Carte de p\u00eache : 6 \u20ac la journ\u00e9e <br>(2 lignes)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><path d=\"M384 256C384 238.3 398.3 224 416 224C433.7 224 448 238.3 448 256C448 273.7 433.7 288 416 288C398.3 288 384 273.7 384 256zM416 240C407.2 240 400 247.2 400 256C400 264.8 407.2 272 416 272C424.8 272 432 264.8 432 256C432 247.2 424.8 240 416 240zM180.5 370.5C164.3 356.7 150 341.9 137.8 327.3L48.12 379.6C35.61 386.9 19.76 384.9 9.474 374.7C-.8133 364.5-2.97 348.7 4.216 336.1L50 256L4.216 175.9C-2.97 163.3-.8133 147.5 9.474 137.3C19.76 127.1 35.61 125.1 48.12 132.4L137.8 184.7C150 170.1 164.3 155.3 180.5 141.5C219.7 108.5 272.6 80 336 80C399.4 80 452.3 108.5 491.5 141.5C530.5 174.5 558.3 213.1 572.4 241.3C577.2 250.5 577.2 261.5 572.4 270.7C558.3 298 530.5 337.5 491.5 370.5C452.3 403.5 399.4 432 336 432C272.6 432 219.7 403.5 180.5 370.5L180.5 370.5zM190.8 358.2C228.2 389.8 277.5 416 336 416C394.5 416 443.8 389.8 481.1 358.2C518.5 326.7 544.1 289 558.2 263.3C560.6 258.7 560.6 253.3 558.2 248.7C544.1 222.1 518.5 185.3 481.1 153.8C443.8 122.2 394.5 96 336 96C277.5 96 228.2 122.2 190.8 153.8C175.4 166.8 161.8 180.1 150.1 194.9L141.5 205.3L40.06 146.2C33.81 142.5 25.88 143.5 20.74 148.6C15.59 153.7 14.51 161.7 18.11 167.9L68.43 255.1L18.11 344.1C14.51 350.3 15.59 358.3 20.74 363.4C25.88 368.5 33.81 369.5 40.06 365.8L141.5 306.7L150.1 317.1C161.8 331 175.4 345.2 190.8 358.2L190.8 358.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Carte carpiste sur demande<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79feee8 elementor-widget elementor-widget-text-editor\" data-id=\"79feee8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><em>le lac et interdit \u00e0 la baignade et aux embarcations type cano\u00eb paddle<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10918de9 e-con-full e-flex e-con e-child\" data-id=\"10918de9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3c4cb5f6 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3c4cb5f6\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;600&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52631ae elementor-widget elementor-widget-image\" data-id=\"52631ae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"512\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/shoe-prints.svg\" class=\"attachment-large size-large wp-image-310\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77a8f0da elementor-widget elementor-widget-heading\" data-id=\"77a8f0da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Balades &amp; Randonn\u00e9es<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-420b8795 elementor-widget elementor-widget-heading\" data-id=\"420b8795\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sentiers faciles et ombrag\u00e9s traversant la for\u00eat et longeant parfois le lac.\nId\u00e9al pour une promenade matinale, une sortie familiale ou une marche romantique au coucher du soleil.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fccff93 e-con-full e-flex e-con e-parent\" data-id=\"fccff93\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-be63500 e-con-full e-flex e-con e-child\" data-id=\"be63500\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0d056e2 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"0d056e2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;400&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-eb91a6b e-con-full e-flex e-con e-child\" data-id=\"eb91a6b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfe87cb elementor-widget elementor-widget-image\" data-id=\"bfe87cb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/bird.svg\" class=\"attachment-large size-large wp-image-275\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9277df elementor-widget elementor-widget-heading\" data-id=\"a9277df\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Observatoire ornithologique<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26576e6 elementor-widget elementor-widget-heading\" data-id=\"26576e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Un observatoire est accessible directement depuis le site.\nNous mettons \u00e0 disposition une paire de jumelles pour admirer les nombreuses esp\u00e8ces d\u2019oiseaux pr\u00e9sentes autour du lac.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a81928 e-con-full e-flex e-con e-child\" data-id=\"9a81928\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1716aae e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1716aae\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;600&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93a69a3 elementor-widget elementor-widget-image\" data-id=\"93a69a3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"512\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/ball-pile.svg\" class=\"attachment-large size-large wp-image-360\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc597c7 elementor-widget elementor-widget-heading\" data-id=\"bc597c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Terrain<br> de p\u00e9tanque<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21f9ae6 elementor-widget elementor-widget-heading\" data-id=\"21f9ae6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Pour des moments conviviaux en famille ou entre amis.\nUne activit\u00e9 simple et interg\u00e9n\u00e9rationnelle, parfaite pour se d\u00e9tendre entre deux balades.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4c1ad6 e-con-full e-flex e-con e-child\" data-id=\"a4c1ad6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe1df15 elementor-widget elementor-widget-image\" data-id=\"fe1df15\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"384\" height=\"512\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/watch-fitness.svg\" class=\"attachment-large size-large wp-image-364\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5068d86 elementor-widget elementor-widget-heading\" data-id=\"5068d86\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Parcours sant\u00e9 \/ fitness nature<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9759c9 elementor-widget elementor-widget-heading\" data-id=\"f9759c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00c0 proximit\u00e9 imm\u00e9diate du domaine, un parcours sant\u00e9 vous permet de bouger en douceur tout en profitant du plein air.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63b54f3 e-con-full e-flex e-con e-parent\" data-id=\"63b54f3\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bbcdc9d e-con-full e-flex e-con e-child\" data-id=\"bbcdc9d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4748693 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"4748693\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bd921e elementor-widget elementor-widget-image\" data-id=\"7bd921e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"448\" height=\"512\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/utensils.svg\" class=\"attachment-large size-large wp-image-314\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66494b9 elementor-widget elementor-widget-heading\" data-id=\"66494b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Acc\u00e8s direct au restaurant L\u2019Impr\u00e9vu<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2f067b elementor-widget elementor-widget-heading\" data-id=\"c2f067b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Situ\u00e9 au bord du lac, ce restaurant appr\u00e9ci\u00e9 offre une cuisine locale et g\u00e9n\u00e9reuse dans un d\u00e9cor naturel exceptionnel.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78d1fd8 e-con-full e-flex e-con e-child\" data-id=\"78d1fd8\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5c05ac1 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"5c05ac1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;400&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-eb207f9 e-con-full e-flex e-con e-child\" data-id=\"eb207f9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a37a182 elementor-widget elementor-widget-image\" data-id=\"a37a182\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"512\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/sunglasses.svg\" class=\"attachment-large size-large wp-image-376\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-797ec06 elementor-widget elementor-widget-heading\" data-id=\"797ec06\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pause d\u00e9tente sur votre terrasse<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45806b3 elementor-widget elementor-widget-heading\" data-id=\"45806b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Chaque h\u00e9bergement dispose d\u2019une terrasse, dont trois sur pilotis avec vue sur le lac.\nUn v\u00e9ritable havre pour :<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a579e93 elementor-mobile-align-center elementor-align-left elementor-widget__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a579e93\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\"><path d=\"M632 32c-4.422 0-8 3.578-8 8v370.4c0 10.95-7.469 20.27-18.17 22.64l-280.8 62.39c-3.281 .75-6.734 .75-10.05 0l-280.8-62.39C23.47 430.7 16 421.4 16 410.4V40C16 35.58 12.42 32 8 32S0 35.58 0 40v370.4c0 18.52 12.62 34.25 30.7 38.27l280.8 62.39C314.3 511.7 317.1 512 320 512s5.719-.3125 8.5-.9375l280.8-62.39C627.4 444.7 640 428.9 640 410.4V40C640 35.58 636.4 32 632 32zM89.06 396.7L320 448l230.9-51.32C565.6 393.4 576 380.4 576 365.4V39.47c0-22.07-17.99-39.46-39.31-39.46c-2.008 0-4.047 .1396-6.102 .458L320 33.13L109.4 .4707C107.4 .1523 105.3 .0127 103.3 .0127C81.99 .0107 64 17.4 64 39.47v325.1C64 380.4 74.42 393.4 89.06 396.7zM328 48.02l205-31.73c1.23-.1895 2.451-.2832 3.654-.2832C549.5 15.1 560 26.49 560 39.39v326c0 7.557-5.152 13.98-12.53 15.62L328 429.8V48.02zM80 39.39c0-6.293 2.457-12.19 6.916-16.6C91.34 18.41 97.16 15.1 103.3 15.1c1.203 0 2.426 .0938 3.656 .2832L312 48.02V429.8l-219.5-48.77C85.15 379.4 80 372.1 80 365.4V39.39z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lire<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M368 0c-53.09 0-101.7 29.22-126.9 76.22C239.1 80.13 240.5 84.97 244.4 87.06C248.3 89.09 253.2 87.69 255.3 83.78C277.6 41.97 320.8 16 368 16c70.59 0 127.1 57.41 127.1 128c0 63.38-45.69 116.4-108.6 126c-4.375 .6562-7.344 4.75-6.688 9.125c.5938 3.938 4 6.781 7.906 6.781c.4062 0 .8125-.0313 1.219-.0938C460.6 275 512 215.3 512 144C512 64.59 447.4 0 368 0zM319.1 128H32.02c-8.998 0-17.62 3.875-23.75 10.5c-6 6.75-8.998 15.62-8.123 24.62l31.99 319.1C33.77 499.5 47.52 512 64.02 512h223.1c16.5 0 30.25-12.5 31.87-28.87l32-319.1c.875-9-2.124-17.87-8.124-24.62C337.6 131.9 328.1 128 319.1 128zM303.9 481.5C303.1 489.8 296.3 496 287.1 496H64.02c-8.275 0-15.13-6.215-15.95-14.46L25.52 256h300.1L303.9 481.5zM328.1 240h-304.2L16.08 161.6C15.14 151.1 22.78 144 32.02 144h287.1c13.47 0 16.41 12.77 15.95 17.54L328.1 240z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Partager un ap\u00e9ro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M486.2 39.98C483.8 34.67 478.8 32 473.8 32c-4.744 0-9.547 2.379-12.3 7.156c-24.99 43.27-70.11 65.15-115.9 65.15c-11.18 0-22.41-1.304-33.39-3.917c-12.9-3.07-26.34-4.527-40.18-4.527C174.8 95.86 96 174.8 96 272c0 11.16 1.116 22.04 3.101 32.61c-.0215 .0195 .0215-.0156 0 0C13.19 372.1 .5469 467 .0625 471c-.5469 4.375 2.578 8.375 6.953 8.906C7.359 479.1 7.688 480 8.016 480c3.969 0 7.422-2.969 7.922-7.031c.1074-.8828 11.83-87.79 87.37-150.1c21.55 72.84 88.88 126 168.7 126c22.87 0 44.65-4.518 64.69-12.46C441.9 400.7 512 293.2 512 165.4C512 121.9 502.7 76.76 486.2 39.98zM330.8 420.7C311.9 428.2 292.1 431.1 272 432c-88.22 0-160-71.78-160-160s71.78-160 160-160l7.047-.1211c10.02 .4375 19.89 1.801 29.45 4.078c12.13 2.887 24.62 4.352 37.1 4.352c53.44 0 100.9-25.99 127.8-69.74C487.8 84.48 496 126 496 165.4C496 285.4 429.1 387.8 330.8 420.7zM348.6 192c-13.6 0-27.34 5.512-37.53 15.82l-7.188 7.188l-7.188-7.188C286.5 197.5 272.8 192 259.3 192c-10.84 0-21.61 3.52-30.5 10.92C205.9 222.1 204.6 256.5 225.1 277.2l70.63 71.36C298.1 350.9 301 352 304 352c2.967 0 5.936-1.145 8.229-3.438l70.63-71.36c20.52-20.73 19.27-55.11-3.75-74.28C370.3 195.5 359.5 192 348.6 192zM371.5 265.9L304 334.1L236.5 265.9C229.8 259.2 226.2 249.8 226.7 240.1c.459-9.777 4.861-18.63 12.37-24.91C244.7 210.5 251.7 208 259.3 208c9.6 0 19.09 4.035 26.11 11.13l18.5 18.5l18.57-18.57C329.4 212 338.9 208 348.6 208c7.615 0 14.61 2.484 20.26 7.219c7.561 6.293 11.98 15.14 12.46 24.92C381.8 249.8 378.2 259.2 371.5 265.9z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contempler la nature<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 136C189.7 136 136 189.7 136 256c0 66.27 53.72 120 120 120s120-53.73 120-120C376 189.7 322.3 136 256 136zM256 360c-57.35 0-104-46.65-104-104S198.7 152 256 152S360 198.7 360 256S313.3 360 256 360zM256 112c4.422 0 8-3.578 8-8v-96C264 3.578 260.4 0 256 0S248 3.578 248 8v96C248 108.4 251.6 112 256 112zM256 400c-4.422 0-8 3.578-8 8v96C248 508.4 251.6 512 256 512s8-3.578 8-8v-96C264 403.6 260.4 400 256 400zM504 248h-96c-4.422 0-8 3.578-8 8s3.578 8 8 8h96C508.4 264 512 260.4 512 256S508.4 248 504 248zM112 256c0-4.422-3.578-8-8-8h-96C3.578 248 0 251.6 0 256s3.578 8 8 8h96C108.4 264 112 260.4 112 256zM363.5 156.5c2.047 0 4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.188 0-11.31s-8.188-3.125-11.31 0l-52.52 52.52c-3.125 3.125-3.125 8.2 0 11.32C359.4 155.7 361.4 156.5 363.5 156.5zM142.9 357.8l-52.52 52.52c-3.125 3.125-3.125 8.188 0 11.31C91.91 423.2 93.95 424 96 424s4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.2 0-11.33S145.1 354.7 142.9 357.8zM369.1 357.8c-3.125-3.125-8.188-3.138-11.31-.0125s-3.125 8.2 0 11.33l52.52 52.52C411.9 423.2 413.1 424 416 424s4.094-.7813 5.656-2.344c3.125-3.125 3.125-8.188 0-11.31L369.1 357.8zM142.9 154.2c1.562 1.562 3.609 2.344 5.656 2.344S152.6 155.7 154.2 154.2c3.125-3.125 3.125-8.2 0-11.32L101.7 90.34c-3.125-3.125-8.188-3.125-11.31 0s-3.125 8.188 0 11.31L142.9 154.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ecouter le silence<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fd45b7 e-con-full e-flex e-con e-child\" data-id=\"5fd45b7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d043725 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"d043725\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;600&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-347c29d elementor-widget elementor-widget-image\" data-id=\"347c29d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"384\" height=\"512\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/child-reaching.svg\" class=\"attachment-large size-large wp-image-368\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9654e8d elementor-widget elementor-widget-heading\" data-id=\"9654e8d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Petites aires de jeux pour enfants<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f1dfde elementor-widget elementor-widget-heading\" data-id=\"9f1dfde\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Parfait pour occuper les plus jeunes, l'aire de jeux pour les enfants se trouvent au bord du lac (sous la responsabilit\u00e9 des parents)<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d0d8aa7 e-flex e-con-boxed e-con e-parent\" data-id=\"6d0d8aa7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-21b5af3e e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"21b5af3e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:&quot;200&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64e76235 elementor-widget elementor-widget-heading\" data-id=\"64e76235\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Nos services sur place<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe67665 elementor-widget elementor-widget-heading\" data-id=\"2fe67665\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Options gourmandes &amp; moments \u00e0 partager<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-127a5d5d elementor-widget elementor-widget-heading\" data-id=\"127a5d5d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sur place, une gamme de services vous sera propos\u00e9e\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65f91f37 e-con-full e-flex e-con e-child\" data-id=\"65f91f37\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6567c276 e-con-full e-flex e-con e-child\" data-id=\"6567c276\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-31a3e40e e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"31a3e40e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41c59ef elementor-widget elementor-widget-heading\" data-id=\"41c59ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Planche compagnarde (charcuteries &amp; fromages)\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bad27c4 elementor-widget elementor-widget-heading\" data-id=\"2bad27c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Planche mixte pour 2 personnes: 30\u20ac<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1492fc elementor-tablet-align-center elementor-align-left elementor-widget elementor-widget-button\" data-id=\"d1492fc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 136C189.7 136 136 189.7 136 256c0 66.27 53.72 120 120 120s120-53.73 120-120C376 189.7 322.3 136 256 136zM256 360c-57.35 0-104-46.65-104-104S198.7 152 256 152S360 198.7 360 256S313.3 360 256 360zM256 112c4.422 0 8-3.578 8-8v-96C264 3.578 260.4 0 256 0S248 3.578 248 8v96C248 108.4 251.6 112 256 112zM256 400c-4.422 0-8 3.578-8 8v96C248 508.4 251.6 512 256 512s8-3.578 8-8v-96C264 403.6 260.4 400 256 400zM504 248h-96c-4.422 0-8 3.578-8 8s3.578 8 8 8h96C508.4 264 512 260.4 512 256S508.4 248 504 248zM112 256c0-4.422-3.578-8-8-8h-96C3.578 248 0 251.6 0 256s3.578 8 8 8h96C108.4 264 112 260.4 112 256zM363.5 156.5c2.047 0 4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.188 0-11.31s-8.188-3.125-11.31 0l-52.52 52.52c-3.125 3.125-3.125 8.2 0 11.32C359.4 155.7 361.4 156.5 363.5 156.5zM142.9 357.8l-52.52 52.52c-3.125 3.125-3.125 8.188 0 11.31C91.91 423.2 93.95 424 96 424s4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.2 0-11.33S145.1 354.7 142.9 357.8zM369.1 357.8c-3.125-3.125-8.188-3.138-11.31-.0125s-3.125 8.2 0 11.33l52.52 52.52C411.9 423.2 413.1 424 416 424s4.094-.7813 5.656-2.344c3.125-3.125 3.125-8.188 0-11.31L369.1 357.8zM142.9 154.2c1.562 1.562 3.609 2.344 5.656 2.344S152.6 155.7 154.2 154.2c3.125-3.125 3.125-8.2 0-11.32L101.7 90.34c-3.125-3.125-8.188-3.125-11.31 0s-3.125 8.188 0 11.31L142.9 154.2z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">A s\u00e9lectionner durant votre r\u00e9servation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0680892 e-con-full e-flex e-con e-child\" data-id=\"0680892\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-bc3b1cc e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"bc3b1cc\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46a535f elementor-widget elementor-widget-heading\" data-id=\"46a535f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">kota grill panier BBQ<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3252f19 elementor-widget elementor-widget-heading\" data-id=\"3252f19\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">pour 2 personnes 40 euros pour 4 personnes 80 euros<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f38b3f0 elementor-tablet-align-center elementor-align-left elementor-widget elementor-widget-button\" data-id=\"f38b3f0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 136C189.7 136 136 189.7 136 256c0 66.27 53.72 120 120 120s120-53.73 120-120C376 189.7 322.3 136 256 136zM256 360c-57.35 0-104-46.65-104-104S198.7 152 256 152S360 198.7 360 256S313.3 360 256 360zM256 112c4.422 0 8-3.578 8-8v-96C264 3.578 260.4 0 256 0S248 3.578 248 8v96C248 108.4 251.6 112 256 112zM256 400c-4.422 0-8 3.578-8 8v96C248 508.4 251.6 512 256 512s8-3.578 8-8v-96C264 403.6 260.4 400 256 400zM504 248h-96c-4.422 0-8 3.578-8 8s3.578 8 8 8h96C508.4 264 512 260.4 512 256S508.4 248 504 248zM112 256c0-4.422-3.578-8-8-8h-96C3.578 248 0 251.6 0 256s3.578 8 8 8h96C108.4 264 112 260.4 112 256zM363.5 156.5c2.047 0 4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.188 0-11.31s-8.188-3.125-11.31 0l-52.52 52.52c-3.125 3.125-3.125 8.2 0 11.32C359.4 155.7 361.4 156.5 363.5 156.5zM142.9 357.8l-52.52 52.52c-3.125 3.125-3.125 8.188 0 11.31C91.91 423.2 93.95 424 96 424s4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.2 0-11.33S145.1 354.7 142.9 357.8zM369.1 357.8c-3.125-3.125-8.188-3.138-11.31-.0125s-3.125 8.2 0 11.33l52.52 52.52C411.9 423.2 413.1 424 416 424s4.094-.7813 5.656-2.344c3.125-3.125 3.125-8.188 0-11.31L369.1 357.8zM142.9 154.2c1.562 1.562 3.609 2.344 5.656 2.344S152.6 155.7 154.2 154.2c3.125-3.125 3.125-8.2 0-11.32L101.7 90.34c-3.125-3.125-8.188-3.125-11.31 0s-3.125 8.188 0 11.31L142.9 154.2z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">A s\u00e9lectionner durant votre r\u00e9servation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-91e6c27 e-con-full e-flex e-con e-child\" data-id=\"91e6c27\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1db5449 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1db5449\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cba8228 elementor-widget elementor-widget-heading\" data-id=\"cba8228\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">kota grill panier du viandard<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54c8eb0 elementor-widget elementor-widget-heading\" data-id=\"54c8eb0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">pour 2 personnes 60 euros pour 4 personnes 120euros<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaee94e elementor-tablet-align-center elementor-align-left elementor-widget elementor-widget-button\" data-id=\"eaee94e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 136C189.7 136 136 189.7 136 256c0 66.27 53.72 120 120 120s120-53.73 120-120C376 189.7 322.3 136 256 136zM256 360c-57.35 0-104-46.65-104-104S198.7 152 256 152S360 198.7 360 256S313.3 360 256 360zM256 112c4.422 0 8-3.578 8-8v-96C264 3.578 260.4 0 256 0S248 3.578 248 8v96C248 108.4 251.6 112 256 112zM256 400c-4.422 0-8 3.578-8 8v96C248 508.4 251.6 512 256 512s8-3.578 8-8v-96C264 403.6 260.4 400 256 400zM504 248h-96c-4.422 0-8 3.578-8 8s3.578 8 8 8h96C508.4 264 512 260.4 512 256S508.4 248 504 248zM112 256c0-4.422-3.578-8-8-8h-96C3.578 248 0 251.6 0 256s3.578 8 8 8h96C108.4 264 112 260.4 112 256zM363.5 156.5c2.047 0 4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.188 0-11.31s-8.188-3.125-11.31 0l-52.52 52.52c-3.125 3.125-3.125 8.2 0 11.32C359.4 155.7 361.4 156.5 363.5 156.5zM142.9 357.8l-52.52 52.52c-3.125 3.125-3.125 8.188 0 11.31C91.91 423.2 93.95 424 96 424s4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.2 0-11.33S145.1 354.7 142.9 357.8zM369.1 357.8c-3.125-3.125-8.188-3.138-11.31-.0125s-3.125 8.2 0 11.33l52.52 52.52C411.9 423.2 413.1 424 416 424s4.094-.7813 5.656-2.344c3.125-3.125 3.125-8.188 0-11.31L369.1 357.8zM142.9 154.2c1.562 1.562 3.609 2.344 5.656 2.344S152.6 155.7 154.2 154.2c3.125-3.125 3.125-8.2 0-11.32L101.7 90.34c-3.125-3.125-8.188-3.125-11.31 0s-3.125 8.188 0 11.31L142.9 154.2z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">A s\u00e9lectionner durant votre r\u00e9servation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c27e806 e-con-full e-flex e-con e-child\" data-id=\"c27e806\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7300a6f e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"7300a6f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74bfe98 elementor-widget elementor-widget-heading\" data-id=\"74bfe98\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Planche romantique<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc3a2b9 elementor-widget elementor-widget-heading\" data-id=\"cc3a2b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">avec petite d\u00e9coration de l'h\u00e9bergement \n&amp; cocktail sans alcool\n50\u20ac<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0f870d elementor-tablet-align-center elementor-align-left elementor-widget elementor-widget-button\" data-id=\"d0f870d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 136C189.7 136 136 189.7 136 256c0 66.27 53.72 120 120 120s120-53.73 120-120C376 189.7 322.3 136 256 136zM256 360c-57.35 0-104-46.65-104-104S198.7 152 256 152S360 198.7 360 256S313.3 360 256 360zM256 112c4.422 0 8-3.578 8-8v-96C264 3.578 260.4 0 256 0S248 3.578 248 8v96C248 108.4 251.6 112 256 112zM256 400c-4.422 0-8 3.578-8 8v96C248 508.4 251.6 512 256 512s8-3.578 8-8v-96C264 403.6 260.4 400 256 400zM504 248h-96c-4.422 0-8 3.578-8 8s3.578 8 8 8h96C508.4 264 512 260.4 512 256S508.4 248 504 248zM112 256c0-4.422-3.578-8-8-8h-96C3.578 248 0 251.6 0 256s3.578 8 8 8h96C108.4 264 112 260.4 112 256zM363.5 156.5c2.047 0 4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.188 0-11.31s-8.188-3.125-11.31 0l-52.52 52.52c-3.125 3.125-3.125 8.2 0 11.32C359.4 155.7 361.4 156.5 363.5 156.5zM142.9 357.8l-52.52 52.52c-3.125 3.125-3.125 8.188 0 11.31C91.91 423.2 93.95 424 96 424s4.094-.7813 5.656-2.344l52.52-52.52c3.125-3.125 3.125-8.2 0-11.33S145.1 354.7 142.9 357.8zM369.1 357.8c-3.125-3.125-8.188-3.138-11.31-.0125s-3.125 8.2 0 11.33l52.52 52.52C411.9 423.2 413.1 424 416 424s4.094-.7813 5.656-2.344c3.125-3.125 3.125-8.188 0-11.31L369.1 357.8zM142.9 154.2c1.562 1.562 3.609 2.344 5.656 2.344S152.6 155.7 154.2 154.2c3.125-3.125 3.125-8.2 0-11.32L101.7 90.34c-3.125-3.125-8.188-3.125-11.31 0s-3.125 8.188 0 11.31L142.9 154.2z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">A s\u00e9lectionner durant votre r\u00e9servation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f89bc1d e-con-full e-flex e-con e-parent\" data-id=\"6f89bc1d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2106cddd e-con-full e-flex e-con e-child\" data-id=\"2106cddd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4d0bf118 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"4d0bf118\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd82823 elementor-widget elementor-widget-heading\" data-id=\"fd82823\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Galerie photos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f976c08 elementor-widget elementor-widget-heading\" data-id=\"3f976c08\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Un peu d'eau \u00e0 la bouche<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59877f7 elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"59877f7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9servation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-225097bf e-con-full e-flex e-con e-child\" data-id=\"225097bf\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6e55ec70 e-con-full e-flex e-con e-child\" data-id=\"6e55ec70\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4274d819 e-con-full e-flex e-con e-child\" data-id=\"4274d819\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ce22d54 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6ce22d54\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;2&quot;,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;],&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;400&quot;,&quot;motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}}}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/0-4-1024x576.jpg\" class=\"attachment-large size-large wp-image-1432\" alt=\"\" srcset=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/0-4-1024x576.jpg 1024w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/0-4-768x432.jpg 768w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/0-4-1536x864.jpg 1536w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/0-4-2048x1153.jpg 2048w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/0-4-200x113.jpg 200w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/0-4-320x180.jpg 320w, https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/0-4-480x270.jpg 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67264e21 e-con-full e-flex e-con e-child\" data-id=\"67264e21\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17db603c e-con-full e-flex e-con e-parent\" data-id=\"17db603c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-67def6fd e-con-full e-flex e-con e-child\" data-id=\"67def6fd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-690e6f66 e-con-full e-flex e-con e-child\" data-id=\"690e6f66\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30267756 e-con-full e-flex e-con e-child\" data-id=\"30267756\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4dcf4b39 e-con-full e-flex e-con e-child\" data-id=\"4dcf4b39\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d9a56e elementor-testimonial--skin-bubble elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-invisible elementor-widget elementor-widget-testimonial-carousel\" data-id=\"5d9a56e\" data-element_type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;400&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tLaissez-vous r\u00e9veiller par le champ des oiseaux en \u00e9t\u00e9, rideaux ouverts sur le lac, et petit d\u00e9jeuner au lit. \t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/cropped-logo-1-300x300.png\" alt=\"Les Cabanes\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Les Cabanes<\/span><span class=\"elementor-testimonial__title\">En \u00e9t\u00e9<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tLaissez-vous surprendre par le manteau de neige en hiver, brumes matinal et promenade enchanteresses\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/cropped-logo-1-300x300.png\" alt=\"Les cabanes\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Les cabanes<\/span><span class=\"elementor-testimonial__title\">en hiver<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63425727 e-con-full e-flex e-con e-child\" data-id=\"63425727\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Slow Living atypique au bord d&rsquo;un lac Les Cabanes JU &amp; CO Entre for\u00eat et lac, d\u00e9couvrez une parenth\u00e8se suspendue, pens\u00e9e pour la d\u00e9tente, l\u2019\u00e9vasion et les instants pr\u00e9cieux en famille ou en amoureux. Un endroit convivial O\u00f9 l&rsquo;on vient faire des rencontres &#8230; o\u00f9 l&rsquo;on respire. Profitez du lac P\u00eache ou d\u00e9tente, \u00e0 vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1273,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-9","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Cabanes Ju &amp; Co | Les Cabanes Ju &amp; Co<\/title>\n<meta name=\"description\" content=\"Les Cabanes Ju &amp; Co : slow living entre for\u00eat et lac, s\u00e9jours nature en duo ou famille, d\u00e9tente, p\u00eache, balades. En savoir plus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lescabanesjuandco.fr\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Cabanes Ju &amp; Co | Les Cabanes Ju &amp; Co\" \/>\n<meta property=\"og:description\" content=\"Les Cabanes Ju &amp; Co : slow living entre for\u00eat et lac, s\u00e9jours nature en duo ou famille, d\u00e9tente, p\u00eache, balades. En savoir plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lescabanesjuandco.fr\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Cabanes Ju &amp; Co\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61578727172142\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T21:51:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/tonneau-1000050740.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2040\" \/>\n\t<meta property=\"og:image:height\" content=\"1148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lescabanesjuandco.fr\/\",\"url\":\"https:\/\/lescabanesjuandco.fr\/\",\"name\":\"Les Cabanes Ju &amp; Co | Les Cabanes Ju &amp; Co\",\"isPartOf\":{\"@id\":\"https:\/\/lescabanesjuandco.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lescabanesjuandco.fr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lescabanesjuandco.fr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/tonneau-1000050740.jpg\",\"datePublished\":\"2025-11-18T12:05:30+00:00\",\"dateModified\":\"2026-03-23T21:51:20+00:00\",\"description\":\"Les Cabanes Ju & Co : slow living entre for\u00eat et lac, s\u00e9jours nature en duo ou famille, d\u00e9tente, p\u00eache, balades. En savoir plus\",\"breadcrumb\":{\"@id\":\"https:\/\/lescabanesjuandco.fr\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lescabanesjuandco.fr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/lescabanesjuandco.fr\/#primaryimage\",\"url\":\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/tonneau-1000050740.jpg\",\"contentUrl\":\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/tonneau-1000050740.jpg\",\"width\":2040,\"height\":1148},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lescabanesjuandco.fr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/lescabanesjuandco.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Cabanes Ju &amp; Co\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lescabanesjuandco.fr\/#website\",\"url\":\"https:\/\/lescabanesjuandco.fr\/\",\"name\":\"Les Cabanes Ju & Co\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/lescabanesjuandco.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lescabanesjuandco.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lescabanesjuandco.fr\/#organization\",\"name\":\"Les Cabanes Ju & Co\",\"url\":\"https:\/\/lescabanesjuandco.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/lescabanesjuandco.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo.png\",\"contentUrl\":\"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo.png\",\"width\":2211,\"height\":2211,\"caption\":\"Les Cabanes Ju & Co\"},\"image\":{\"@id\":\"https:\/\/lescabanesjuandco.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61578727172142\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Cabanes Ju &amp; Co | Les Cabanes Ju &amp; Co","description":"Les Cabanes Ju &amp; Co: slow living between forest and lake, nature stays for couples or families, relaxation, fishing, walks. Find out more","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lescabanesjuandco.fr\/en\/","og_locale":"en_GB","og_type":"article","og_title":"Les Cabanes Ju &amp; Co | Les Cabanes Ju &amp; Co","og_description":"Les Cabanes Ju & Co : slow living entre for\u00eat et lac, s\u00e9jours nature en duo ou famille, d\u00e9tente, p\u00eache, balades. En savoir plus","og_url":"https:\/\/lescabanesjuandco.fr\/en\/","og_site_name":"Les Cabanes Ju &amp; Co","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61578727172142","article_modified_time":"2026-03-23T21:51:20+00:00","og_image":[{"width":2040,"height":1148,"url":"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/tonneau-1000050740.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lescabanesjuandco.fr\/","url":"https:\/\/lescabanesjuandco.fr\/","name":"Les Cabanes Ju &amp; Co | Les Cabanes Ju &amp; Co","isPartOf":{"@id":"https:\/\/lescabanesjuandco.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lescabanesjuandco.fr\/#primaryimage"},"image":{"@id":"https:\/\/lescabanesjuandco.fr\/#primaryimage"},"thumbnailUrl":"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/tonneau-1000050740.jpg","datePublished":"2025-11-18T12:05:30+00:00","dateModified":"2026-03-23T21:51:20+00:00","description":"Les Cabanes Ju &amp; Co: slow living between forest and lake, nature stays for couples or families, relaxation, fishing, walks. Find out more","breadcrumb":{"@id":"https:\/\/lescabanesjuandco.fr\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lescabanesjuandco.fr\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lescabanesjuandco.fr\/#primaryimage","url":"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/tonneau-1000050740.jpg","contentUrl":"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2026\/03\/tonneau-1000050740.jpg","width":2040,"height":1148},{"@type":"BreadcrumbList","@id":"https:\/\/lescabanesjuandco.fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lescabanesjuandco.fr\/"},{"@type":"ListItem","position":2,"name":"Les Cabanes Ju &amp; Co"}]},{"@type":"WebSite","@id":"https:\/\/lescabanesjuandco.fr\/#website","url":"https:\/\/lescabanesjuandco.fr\/","name":"Ju &amp; Co Cabins","description":"","publisher":{"@id":"https:\/\/lescabanesjuandco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lescabanesjuandco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/lescabanesjuandco.fr\/#organization","name":"Ju &amp; Co Cabins","url":"https:\/\/lescabanesjuandco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lescabanesjuandco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo.png","contentUrl":"https:\/\/lescabanesjuandco.fr\/wp-content\/uploads\/2025\/12\/logo.png","width":2211,"height":2211,"caption":"Les Cabanes Ju & Co"},"image":{"@id":"https:\/\/lescabanesjuandco.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61578727172142"]}]}},"_links":{"self":[{"href":"https:\/\/lescabanesjuandco.fr\/en\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lescabanesjuandco.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lescabanesjuandco.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lescabanesjuandco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lescabanesjuandco.fr\/en\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":4,"href":"https:\/\/lescabanesjuandco.fr\/en\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":1569,"href":"https:\/\/lescabanesjuandco.fr\/en\/wp-json\/wp\/v2\/pages\/9\/revisions\/1569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lescabanesjuandco.fr\/en\/wp-json\/wp\/v2\/media\/1273"}],"wp:attachment":[{"href":"https:\/\/lescabanesjuandco.fr\/en\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}